{"id":9897,"date":"2019-11-20T13:00:18","date_gmt":"2019-11-20T11:00:18","guid":{"rendered":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg"},"modified":"2019-11-20T13:00:18","modified_gmt":"2019-11-20T11:00:18","slug":"kalev-spa-fitness-center-2","status":"inherit","type":"attachment","link":"https:\/\/ehrl.ee\/en\/member\/linda-restaurant\/kalev-spa-fitness-center-2\/","title":{"rendered":"Kalev Spa fitness center"},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-9897","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kalev Spa fitness center - Eesti Hotellide ja Restoranide Liit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kalev Spa fitness center - Eesti Hotellide ja Restoranide Liit\" \/>\n<meta property=\"og:description\" content=\"Kalev Spa fitness center\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Eesti Hotellide ja Restoranide Liit\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-1024x731.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Kalev-Spa-fitness-center.jpg\",\"url\":\"https:\\\/\\\/ehrl.ee\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Kalev-Spa-fitness-center.jpg\",\"name\":\"Kalev Spa fitness center - Eesti Hotellide ja Restoranide Liit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#website\"},\"datePublished\":\"2019-11-20T11:00:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Kalev-Spa-fitness-center.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ehrl.ee\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Kalev-Spa-fitness-center.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Kalev-Spa-fitness-center.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allee Restaurant\",\"item\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/member\\\/linda-restaurant\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kalev Spa fitness center\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#website\",\"url\":\"https:\\\/\\\/ehrl.ee\\\/\",\"name\":\"Eesti Hotellide ja Restoranide Liit\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ehrl.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kalev Spa fitness center - Eesti Hotellide ja Restoranide Liit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg","og_locale":"en_US","og_type":"article","og_title":"Kalev Spa fitness center - Eesti Hotellide ja Restoranide Liit","og_description":"Kalev Spa fitness center","og_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg","og_site_name":"Eesti Hotellide ja Restoranide Liit","og_image":[{"width":1024,"height":731,"url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-1024x731.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg","url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg","name":"Kalev Spa fitness center - Eesti Hotellide ja Restoranide Liit","isPartOf":{"@id":"https:\/\/ehrl.ee\/#website"},"datePublished":"2019-11-20T11:00:18+00:00","breadcrumb":{"@id":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ehrl.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Allee Restaurant","item":"https:\/\/ehrl.ee\/en\/member\/linda-restaurant\/"},{"@type":"ListItem","position":3,"name":"Kalev Spa fitness center"}]},{"@type":"WebSite","@id":"https:\/\/ehrl.ee\/#website","url":"https:\/\/ehrl.ee\/","name":"Eesti Hotellide ja Restoranide Liit","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ehrl.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-300x214.jpg 300w, https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-768x549.jpg 768w, https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-1024x731.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Kalev Spa fitness center<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2100,"height":1500,"file":"2017\/02\/Kalev-Spa-fitness-center.jpg","sizes":{"thumbnail":{"file":"Kalev-Spa-fitness-center-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-150x150.jpg"},"medium":{"file":"Kalev-Spa-fitness-center-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-300x214.jpg"},"medium_large":{"file":"Kalev-Spa-fitness-center-768x549.jpg","width":768,"height":549,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-768x549.jpg"},"large":{"file":"Kalev-Spa-fitness-center-1024x731.jpg","width":1024,"height":731,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-1024x731.jpg"},"object_image":{"file":"Kalev-Spa-fitness-center-650x360.jpg","width":650,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-650x360.jpg"},"gallery_thumb":{"file":"Kalev-Spa-fitness-center-160x90.jpg","width":160,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-160x90.jpg"},"slide":{"file":"Kalev-Spa-fitness-center-1900x500.jpg","width":1900,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center-1900x500.jpg"},"full":{"file":"Kalev-Spa-fitness-center.jpg","width":2100,"height":1500,"mime_type":"image\/jpeg","source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg"}},"image_meta":{"aperture":"9","credit":"","camera":"Canon EOS 5DS R","caption":"Kalev Spa fitness center","created_timestamp":"1552918024","copyright":"","focal_length":"20","iso":"320","shutter_speed":"0.0333333333333","title":"Kalev Spa fitness center","orientation":"1","keywords":[]}},"post":3849,"source_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/02\/Kalev-Spa-fitness-center.jpg","_links":{"self":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/media\/9897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/comments?post=9897"}],"wp:attached-to":[{"embeddable":true,"post_type":"member","id":3849,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/member\/3849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}