{"id":4535,"date":"2017-09-12T13:51:10","date_gmt":"2017-09-12T11:51:10","guid":{"rendered":"http:\/\/ehrl.ee\/?p=4535\/"},"modified":"2017-09-12T13:51:10","modified_gmt":"2017-09-12T11:51:10","slug":"press-release-guestjoy-signs-contract-tallink-hotels","status":"publish","type":"post","link":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/","title":{"rendered":"Press release: GuestJoy signs contract with Tallink Hotels"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"class_list":["post-4535","post","type-post","status-publish","format-standard","hentry","category-media"],"acf":{"block_repeater":false,"post_external_url":"https:\/\/ehrl.ee\/wp-content\/uploads\/2017\/09\/GuestJoy-signs-a-contract-with-Tallink-Hotels.pdf"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Press release: GuestJoy signs contract with Tallink Hotels - Eesti Hotellide ja Restoranide Liit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Press release: GuestJoy signs contract with Tallink Hotels - Eesti Hotellide ja Restoranide Liit\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/\" \/>\n<meta property=\"og:site_name\" content=\"Eesti Hotellide ja Restoranide Liit\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-12T11:51:10+00:00\" \/>\n<meta name=\"author\" content=\"Kristi Toiger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kristi Toiger\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/\"},\"author\":{\"name\":\"Kristi Toiger\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#\\\/schema\\\/person\\\/0f299454a508a1e32bf95f0d02e7fb94\"},\"headline\":\"Press release: GuestJoy signs contract with Tallink Hotels\",\"datePublished\":\"2017-09-12T11:51:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/\"},\"wordCount\":8,\"articleSection\":[\"Media\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/\",\"url\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/\",\"name\":\"Press release: GuestJoy signs contract with Tallink Hotels - Eesti Hotellide ja Restoranide Liit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#website\"},\"datePublished\":\"2017-09-12T11:51:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#\\\/schema\\\/person\\\/0f299454a508a1e32bf95f0d02e7fb94\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/2017\\\/09\\\/12\\\/press-release-guestjoy-signs-contract-tallink-hotels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press release: GuestJoy signs contract with Tallink Hotels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#website\",\"url\":\"https:\\\/\\\/ehrl.ee\\\/\",\"name\":\"Eesti Hotellide ja Restoranide Liit\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ehrl.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ehrl.ee\\\/#\\\/schema\\\/person\\\/0f299454a508a1e32bf95f0d02e7fb94\",\"name\":\"Kristi Toiger\",\"url\":\"https:\\\/\\\/ehrl.ee\\\/en\\\/author\\\/kristi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Press release: GuestJoy signs contract with Tallink Hotels - Eesti Hotellide ja Restoranide Liit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/","og_locale":"en_US","og_type":"article","og_title":"Press release: GuestJoy signs contract with Tallink Hotels - Eesti Hotellide ja Restoranide Liit","og_url":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/","og_site_name":"Eesti Hotellide ja Restoranide Liit","article_published_time":"2017-09-12T11:51:10+00:00","author":"Kristi Toiger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Kristi Toiger"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/#article","isPartOf":{"@id":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/"},"author":{"name":"Kristi Toiger","@id":"https:\/\/ehrl.ee\/#\/schema\/person\/0f299454a508a1e32bf95f0d02e7fb94"},"headline":"Press release: GuestJoy signs contract with Tallink Hotels","datePublished":"2017-09-12T11:51:10+00:00","mainEntityOfPage":{"@id":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/"},"wordCount":8,"articleSection":["Media"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/","url":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/","name":"Press release: GuestJoy signs contract with Tallink Hotels - Eesti Hotellide ja Restoranide Liit","isPartOf":{"@id":"https:\/\/ehrl.ee\/#website"},"datePublished":"2017-09-12T11:51:10+00:00","author":{"@id":"https:\/\/ehrl.ee\/#\/schema\/person\/0f299454a508a1e32bf95f0d02e7fb94"},"breadcrumb":{"@id":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ehrl.ee\/en\/2017\/09\/12\/press-release-guestjoy-signs-contract-tallink-hotels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ehrl.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Press release: GuestJoy signs contract with Tallink Hotels"}]},{"@type":"WebSite","@id":"https:\/\/ehrl.ee\/#website","url":"https:\/\/ehrl.ee\/","name":"Eesti Hotellide ja Restoranide Liit","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ehrl.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/ehrl.ee\/#\/schema\/person\/0f299454a508a1e32bf95f0d02e7fb94","name":"Kristi Toiger","url":"https:\/\/ehrl.ee\/en\/author\/kristi\/"}]}},"_links":{"self":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/posts\/4535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/comments?post=4535"}],"version-history":[{"count":1,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/posts\/4535\/revisions"}],"predecessor-version":[{"id":4538,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/posts\/4535\/revisions\/4538"}],"wp:attachment":[{"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/media?parent=4535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ehrl.ee\/en\/wp-json\/wp\/v2\/categories?post=4535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}